{"id":2177,"date":"2019-07-31T00:00:00","date_gmt":"2019-07-31T03:00:00","guid":{"rendered":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/"},"modified":"2023-02-15T18:52:57","modified_gmt":"2023-02-15T21:52:57","slug":"afiliados-para-eventos","status":"publish","type":"post","link":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/","title":{"rendered":"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">J\u00e1 pensou em como seria incr\u00edvel poder contar com uma ajuda extra na hora de vender as inscri\u00e7\u00f5es do seu evento? Nada mau, n\u00e3o \u00e9?! Essa \u00e9 a proposta dos afiliados para eventos, uma ferramenta que tem sido utilizada por muitos organizadores para amplia\u00e7\u00e3o da divulga\u00e7\u00e3o e aumento do n\u00famero de participantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esse \u00e9 um m\u00e9todo utilizado j\u00e1 h\u00e1 um bom tempo na internet, conhecido como marketing de afiliados. E como o <\/span><a href=\"https:\/\/doity.com.br\/blog\/mercado-de-eventos\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">mercado de eventos<\/span><\/a><span style=\"font-weight: 400;\"> n\u00e3o para de se reinventar e buscar solu\u00e7\u00f5es para facilitar a vida do organizador, incorporou essa tend\u00eancia, que tem dado resultado e feito bastante sucesso. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea quer conhecer melhor essa ferramenta e saber porque deve investir nesse pessoal, al\u00e9m de conhecer todos os benef\u00edcios de t\u00ea-los como parceiros, continua lendo esse texto. Voc\u00ea n\u00e3o vai se arrepender! <\/span><\/p>\n<p><strong>Nesse texto voc\u00ea vai aprender:<\/strong><b><\/b><\/p>\n<ul>\n<li><strong><a href=\"#oquesao\">O que s\u00e3o afiliados para eventos<\/a><\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"#vantagens\">Qual a vantagem de ter afiliados para eventos<\/a><\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"#recrutar\">Como recrutar os melhores afiliados<\/a><\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"#montarrede\">E como montar sua rede de afiliados para eventos com alguns cliques!<\/a><\/strong><\/li>\n<\/ul>\n<h2 id=\"oquesao\"><b>O que s\u00e3o afiliados para eventos?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O nome pode n\u00e3o ser t\u00e3o comum, mas essa pr\u00e1tica \u00e9 muita mais antiga do que voc\u00ea imagina! Ela \u00e9, na verdade, uma nova roupagem das vendas <\/span><span style=\"font-weight: 400;\">por comiss\u00e3o, algo feito por comerciantes h\u00e1 muito tempo. Essa pr\u00e1tica \u00e9 feita com o intuito impulsionar as vendas de determinado produto ou servi\u00e7o para alcan\u00e7ar um n\u00famero maior de compradores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com a populariza\u00e7\u00e3o das vendas pela internet, os empres\u00e1rios encontraram mais um espa\u00e7o para comercializar e, assim, os vendedores por comiss\u00e3o passaram a ser chamados de afiliados. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">S\u00f3 que agora, al\u00e9m de fazerem a propaganda de forma pessoal, fazem tamb\u00e9m pelo virtual, como nas redes sociais, em blogs, canais do YouTube, <\/span><a href=\"https:\/\/doity.com.br\/blog\/email-marketing-para-eventos\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">email marketing<\/span><\/a><span style=\"font-weight: 400;\"> entre outros. A \u00fanica mudan\u00e7a de fato acontece no momento da compra que \u00e9 feita, exclusivamente, atrav\u00e9s de um link (falamos mais sobre ele nos pr\u00f3ximos t\u00f3picos).<\/span><\/p>\n<h2 id=\"vantagens\"><b>Qual a vantagem de ter afiliados para eventos?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Acredito que voc\u00ea j\u00e1 deve ter percebido que os afiliados para eventos podem ser \u00fateis na hora de pensar a sua estrat\u00e9gia de <\/span><a href=\"https:\/\/doity.com.br\/blog\/marketing-de-eventos\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">divulga\u00e7\u00e3o e marketing<\/span><\/a><span style=\"font-weight: 400;\">. Mas existem outras vantagens e n\u00e3o custa nada ressaltar como voc\u00ea pode utilizar essa ferramenta. Bora l\u00e1?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A principal delas, sem d\u00favidas, \u00e9 pode contar com pessoas selecionados por voc\u00ea, que sejam confi\u00e1veis e que tenham um bom p\u00fablico, para divulgar o nome do seu evento por a\u00ed. Conseguir unir as suas estrat\u00e9gias de marketing e vendas com as de outra pessoa, que estar\u00e1 trabalhando em paralelo, n\u00e3o tem como dar errado!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O ideal \u00e9 que voc\u00ea selecione afiliados para eventos que estejam pr\u00f3ximos do seu p\u00fablico-alvo como, por exemplo, um estudante que tenha uma boa rede de contatos na universidade. Acredite, fica muito mais f\u00e1cil engajar e criar expectativa nas pessoas quando elas recebem uma indica\u00e7\u00e3o vinda de algu\u00e9m \u201cpr\u00f3ximo\u201d. \u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ah, e al\u00e9m de cuidar de todos os detalhes da organiza\u00e7\u00e3o \u00e9 importante tamb\u00e9m criar uma estrat\u00e9gia de vendas para o seu evento. Atitudes como essa podem garantir que a divulga\u00e7\u00e3o e o marketing sejam mais eficientes. Saiba mais no nosso e-book, \u00e9 gratuito!<\/span><\/p>\n<div class=\"linha_banner_cta\" style=\"background-image: url(https:\/\/doity.com.br\/blog\/app\/uploads\/2018\/10\/ebook-vendas-evento-cta-blog.png);\"><div class=\"linha_banner_email_cta\"><\/div><div class=\"linha_banner_title_text text-cta-right\"><h6>Saiba como vender mais inscri\u00e7\u00f5es e garantir o sucesso do seu evento<\/h6><p>H\u00e1 diversas maneiras de fazer as vendas do seu evento decolarem e torn\u00e1-lo um sucesso. Para ajudar voc\u00ea nessa miss\u00e3o, preparamos este eBook.<\/p><a href=\"http:\/\/materiais.doity.com.br\/ebook-guia-completo-para-aumentar-vendas-evento?utm_source=blog&utm_medium=materiais&_ga=2.141803131.833550132.1560362705-758275922.1552069087\" class=\"cta-post-link\" target=\"blank\">Acessar o conte\u00fado<\/a><\/div><\/div>\n<h2 id=\"recrutar\"><b>Como recrutar os melhores afiliados para eventos?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">J\u00e1 come\u00e7o falando que ter um bom <\/span><a href=\"https:\/\/doity.com.br\/blog\/como-fazer-networking-profissional-em-um-evento\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">networking<\/span><\/a><span style=\"font-weight: 400;\"> ajuda bastante nessa parte! A melhor maneira de escolher afiliados \u00e9 conhecendo pessoas, pesquisando e, claro, vendendo bem seu evento. At\u00e9 porque as pessoas que voc\u00ea recrutar precisam acreditar no seu projeto para que consigam desenvolver uma estrat\u00e9gia de vendas mais eficaz.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Atualmente, existem grandes empresas que recrutam afiliados para os mais diversos ramos e que fazem todo o interm\u00e9dio entre eles e as empresas contratantes. J\u00e1 os organizadores de eventos podem optar pelas plataformas que tamb\u00e9m fazem esse interm\u00e9dio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A vantagem de optar por um <\/span><a href=\"https:\/\/doity.com.br\/blog\/sistema-de-eventos\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">sistema de eventos<\/span><\/a><span style=\"font-weight: 400;\"> \u00e9 que elas conseguem integrar tudo em um \u00fanico lugar, desde gerenciar todas as etapas do evento como tamb\u00e9m fazer o interm\u00e9dio entre afiliados e organizador. Para saber mais sobre essa vantagem \u00e9 s\u00f3 continuar lendo!<\/span><\/p>\n<h2 id=\"montarrede\"><b>Monte sua rede de afiliados com alguns cliques!<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Como j\u00e1 adiantamos l\u00e1 em cima, as facilidades de contar com uma plataforma de eventos s\u00e3o in\u00fameras. Na <\/span><a href=\"https:\/\/doity.com.br\/?utm_source=blog_doity&amp;utm_medium=post&amp;utm_campaign=banner-blog-doity_426\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Doity<\/span><\/a><span style=\"font-weight: 400;\">, por exemplo, a op\u00e7\u00e3o de adicionar afiliados fica dispon\u00edvel no painel do organizador onde \u00e9 poss\u00edvel cadastr\u00e1-lo, inserindo o nome e e-mail da pessoa, para gerar seu c\u00f3digo de identifica\u00e7\u00e3o e escolher a porcentagem que ele ir\u00e1 receber por cada inscri\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 atrav\u00e9s do link gerado no final do cadastro, exclusivo para cada afiliado, que as vendas s\u00e3o feitas. Cada inscri\u00e7\u00e3o realizada atrav\u00e9s deste link contabiliza ao lucro do vendedor e todas as transa\u00e7\u00f5es financeiras s\u00e3o mediadas pela pr\u00f3pria plataforma. Incr\u00edvel, n\u00e9?!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, outra vantagem das plataformas de eventos \u00e9 que elas permitem acompanhar todos os resultados e, assim, analisar se a estrat\u00e9gia de vendas atrav\u00e9s do afiliado est\u00e1 dando resultados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, se a sua d\u00favida agora \u00e9 saber se essa ferramenta se adequa a sua realidade, n\u00f3s te respondemos: s\u00f3 testando para saber! Procure saber mais e n\u00e3o perca a chance de melhorar as vendas do seu evento. Quem sabe essa n\u00e3o pode ser a sa\u00edda que voc\u00ea estava procurando? E qualquer d\u00favida \u00e9 s\u00f3 <\/span><a href=\"https:\/\/doity.com.br\/?utm_source=blog_doity&amp;utm_medium=post&amp;utm_campaign=banner-blog-doity_426\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">entrar em contato com a nossa equipe de atendimento<\/span><\/a><span style=\"font-weight: 400;\"> ou deixar seu coment\u00e1rio aqui no post, vamos amar te ajudar. Afinal, estamos sempre dispon\u00edveis e produzindo conte\u00fados exclusivos para te ajudar a fazer seus neg\u00f3cios decolarem!<\/span><\/p>\n<p><b>E a\u00ed, gostou dessa ferramenta? Temos certeza que voc\u00ea pode conseguir expandir muita mais seus eventos com ela. Ah, e voc\u00ea ainda pode descobrir outras ferramentas incr\u00edveis que a Doity oferece e que n\u00e3o t\u00e3o conhecidas assim aqui <\/b><a href=\"https:\/\/doity.com.br\/blog\/ferramentas-da-doity\/\" target=\"_blank\" rel=\"noopener\"><b>neste texto<\/b><\/a><b>. Garantimos que voc\u00ea n\u00e3o vai se arrepender!<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 pensou em como seria incr\u00edvel poder contar com uma ajuda extra na hora de vender as inscri\u00e7\u00f5es do seu evento? Nada mau, n\u00e3o \u00e9?! Essa \u00e9 a proposta dos afiliados para eventos, uma ferramenta que tem sido utilizada por muitos organizadores para amplia\u00e7\u00e3o da divulga\u00e7\u00e3o e aumento do n\u00famero de participantes. Esse \u00e9 um&hellip;&nbsp;<a href=\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/\" class=\"\" rel=\"bookmark\">LER MAIS<span class=\"screen-reader-text\">Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui!<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":3717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_title":"%%title%% %%sep%% %%sitename%%","_yoast_wpseo_metadesc":"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\u00ea estava procurando na hora de vender as inscri\u00e7\u00f5es do seu evento!","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":""},"categories":[35],"tags":[],"area":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui! - Doity<\/title>\n<meta name=\"description\" content=\"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\u00ea estava procurando na hora de vender as inscri\u00e7\u00f5es do seu evento!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui! - Doity\" \/>\n<meta property=\"og:description\" content=\"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\u00ea estava procurando na hora de vender as inscri\u00e7\u00f5es do seu evento!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/\" \/>\n<meta property=\"og:site_name\" content=\"Doity\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DoityBrasil\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-31T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-15T21:52:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1916\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@doitybrasil\" \/>\n<meta name=\"twitter:site\" content=\"@doitybrasil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Braz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/doity.com.br\/blog\/#organization\",\"name\":\"Doity\",\"url\":\"https:\/\/doity.com.br\/blog\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/DoityBrasil\",\"https:\/\/www.instagram.com\/doitybrasil\/\",\"https:\/\/www.linkedin.com\/company\/doity\/\",\"https:\/\/www.youtube.com\/channel\/UC8RThVprzGquY9wp5EbWH2A\",\"https:\/\/twitter.com\/doitybrasil\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/doity.com.br\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/08\/logo-doity-b.png\",\"contentUrl\":\"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/08\/logo-doity-b.png\",\"width\":800,\"height\":347,\"caption\":\"Doity\"},\"image\":{\"@id\":\"https:\/\/doity.com.br\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/doity.com.br\/blog\/#website\",\"url\":\"https:\/\/doity.com.br\/blog\/\",\"name\":\"Doity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/doity.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/doity.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png\",\"contentUrl\":\"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png\",\"width\":1916,\"height\":534,\"caption\":\"Afiliados para eventos\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#webpage\",\"url\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/\",\"name\":\"Voc\\u00ea sabe o que s\\u00e3o afiliados para eventos? Descubra aqui! - Doity\",\"isPartOf\":{\"@id\":\"https:\/\/doity.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#primaryimage\"},\"datePublished\":\"2019-07-31T03:00:00+00:00\",\"dateModified\":\"2023-02-15T21:52:57+00:00\",\"description\":\"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\\u00ea estava procurando na hora de vender as inscri\\u00e7\\u00f5es do seu evento!\",\"breadcrumb\":{\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"blog\",\"item\":\"https:\/\/doity.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Organizar Eventos\",\"item\":\"https:\/\/doity.com.br\/blog\/categoria\/organizar-eventos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Voc\\u00ea sabe o que s\\u00e3o afiliados para eventos? Descubra aqui!\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#webpage\"},\"author\":{\"@id\":\"https:\/\/doity.com.br\/blog\/#\/schema\/person\/5edc79503cb79e441be3265d147a176f\"},\"headline\":\"Voc\\u00ea sabe o que s\\u00e3o afiliados para eventos? Descubra aqui!\",\"datePublished\":\"2019-07-31T03:00:00+00:00\",\"dateModified\":\"2023-02-15T21:52:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#webpage\"},\"wordCount\":1016,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/doity.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png\",\"articleSection\":[\"Organizar Eventos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/doity.com.br\/blog\/#\/schema\/person\/5edc79503cb79e441be3265d147a176f\",\"name\":\"Aline Braz\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/doity.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5581f75384275e9fdf027537fae34a00?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5581f75384275e9fdf027537fae34a00?s=96&d=mm&r=g\",\"caption\":\"Aline Braz\"},\"description\":\"Jornalista e produtora de conte\\u00fado, movida pela curiosidade e pelo que h\\u00e1 de novo no mundo dos eventos. Apaixonada por m\\u00fasica, livros e viagens!\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui! - Doity","description":"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\u00ea estava procurando na hora de vender as inscri\u00e7\u00f5es do seu evento!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/","og_locale":"pt_BR","og_type":"article","og_title":"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui! - Doity","og_description":"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\u00ea estava procurando na hora de vender as inscri\u00e7\u00f5es do seu evento!","og_url":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/","og_site_name":"Doity","article_publisher":"https:\/\/www.facebook.com\/DoityBrasil","article_published_time":"2019-07-31T03:00:00+00:00","article_modified_time":"2023-02-15T21:52:57+00:00","og_image":[{"width":1916,"height":534,"url":"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@doitybrasil","twitter_site":"@doitybrasil","twitter_misc":{"Written by":"Aline Braz","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/doity.com.br\/blog\/#organization","name":"Doity","url":"https:\/\/doity.com.br\/blog\/","sameAs":["https:\/\/www.facebook.com\/DoityBrasil","https:\/\/www.instagram.com\/doitybrasil\/","https:\/\/www.linkedin.com\/company\/doity\/","https:\/\/www.youtube.com\/channel\/UC8RThVprzGquY9wp5EbWH2A","https:\/\/twitter.com\/doitybrasil"],"logo":{"@type":"ImageObject","@id":"https:\/\/doity.com.br\/blog\/#logo","inLanguage":"pt-BR","url":"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/08\/logo-doity-b.png","contentUrl":"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/08\/logo-doity-b.png","width":800,"height":347,"caption":"Doity"},"image":{"@id":"https:\/\/doity.com.br\/blog\/#logo"}},{"@type":"WebSite","@id":"https:\/\/doity.com.br\/blog\/#website","url":"https:\/\/doity.com.br\/blog\/","name":"Doity","description":"","publisher":{"@id":"https:\/\/doity.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/doity.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png","contentUrl":"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png","width":1916,"height":534,"caption":"Afiliados para eventos"},{"@type":"WebPage","@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#webpage","url":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/","name":"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui! - Doity","isPartOf":{"@id":"https:\/\/doity.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#primaryimage"},"datePublished":"2019-07-31T03:00:00+00:00","dateModified":"2023-02-15T21:52:57+00:00","description":"Descubra como os afiliados para eventos podem ser a ajuda extra que voc\u00ea estava procurando na hora de vender as inscri\u00e7\u00f5es do seu evento!","breadcrumb":{"@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"blog","item":"https:\/\/doity.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Organizar Eventos","item":"https:\/\/doity.com.br\/blog\/categoria\/organizar-eventos\/"},{"@type":"ListItem","position":3,"name":"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui!"}]},{"@type":"Article","@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#article","isPartOf":{"@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#webpage"},"author":{"@id":"https:\/\/doity.com.br\/blog\/#\/schema\/person\/5edc79503cb79e441be3265d147a176f"},"headline":"Voc\u00ea sabe o que s\u00e3o afiliados para eventos? Descubra aqui!","datePublished":"2019-07-31T03:00:00+00:00","dateModified":"2023-02-15T21:52:57+00:00","mainEntityOfPage":{"@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#webpage"},"wordCount":1016,"commentCount":0,"publisher":{"@id":"https:\/\/doity.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#primaryimage"},"thumbnailUrl":"https:\/\/doity.com.br\/blog\/app\/uploads\/2022\/05\/Afiliados-para-eventos.png","articleSection":["Organizar Eventos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/doity.com.br\/blog\/afiliados-para-eventos\/#respond"]}]},{"@type":"Person","@id":"https:\/\/doity.com.br\/blog\/#\/schema\/person\/5edc79503cb79e441be3265d147a176f","name":"Aline Braz","image":{"@type":"ImageObject","@id":"https:\/\/doity.com.br\/blog\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/5581f75384275e9fdf027537fae34a00?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5581f75384275e9fdf027537fae34a00?s=96&d=mm&r=g","caption":"Aline Braz"},"description":"Jornalista e produtora de conte\u00fado, movida pela curiosidade e pelo que h\u00e1 de novo no mundo dos eventos. Apaixonada por m\u00fasica, livros e viagens!"}]}},"_links":{"self":[{"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/posts\/2177"}],"collection":[{"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2177"}],"version-history":[{"count":1,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/posts\/2177\/revisions"}],"predecessor-version":[{"id":2562,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/posts\/2177\/revisions\/2562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/media\/3717"}],"wp:attachment":[{"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2177"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/doity.com.br\/blog\/wp-json\/wp\/v2\/area?post=2177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}